{"id":20554,"date":"2013-01-16T06:00:25","date_gmt":"2013-01-16T06:00:25","guid":{"rendered":"http:\/\/lafeber.com\/vet\/?p=20554"},"modified":"2019-01-21T12:15:03","modified_gmt":"2019-01-21T18:15:03","slug":"catheters-in-reptiles","status":"publish","type":"post","link":"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/","title":{"rendered":"Cat\u00e9teres en Reptiles"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":17656,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[507,333],"tags":[4140,2433,2452,1728,1569],"class_list":["post-20554","post","type-post","status-publish","format-standard","post-password-required","hentry","category-restricted","category-sin-categorizar","tag-cateter-es","tag-intraosea","tag-intravenosa","tag-serpiente","tag-yugular","content_types-articulo","content_types-video-es","topics-cuidado-critico","topics-cuidado-de-apoyo","procedures-cuidado-de-apoyo-es","procedures-fluidoterapia","procedures-terapeutica","species-lagarto","species-reptiles-anfibios","species-serpiente","species-tortugas","channel-medicina-de-emergencia","channel-recursos-y-educacion","contributor-pollock-es","contributor-echols-es","contributor-lichtenberger-es","contributor-diaz-es","rcp-is-restricted","rcp-no-access"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cat\u00e9teres en Reptiles - LafeberVet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cat\u00e9teres en Reptiles - LafeberVet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/\" \/>\n<meta property=\"og:site_name\" content=\"LafeberVet\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-16T06:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-21T18:15:03+00:00\" \/>\n<meta name=\"author\" content=\"Christal Pollock, DVM, DABVP (Avian Practice)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christal Pollock, DVM, DABVP (Avian Practice)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/es\\\/catheters-in-reptiles\\\/\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/es\\\/catheters-in-reptiles\\\/\",\"name\":\"Cat\u00e9teres en Reptiles - LafeberVet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\"},\"datePublished\":\"2013-01-16T06:00:25+00:00\",\"dateModified\":\"2019-01-21T18:15:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/es\\\/catheters-in-reptiles\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/\",\"name\":\"LafeberVet\",\"description\":\"El recurso para los profesionales veterinarios de animales ex\u00f3ticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cat\u00e9teres en Reptiles - LafeberVet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/","og_locale":"es_ES","og_type":"article","og_title":"Cat\u00e9teres en Reptiles - LafeberVet","og_url":"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/","og_site_name":"LafeberVet","article_published_time":"2013-01-16T06:00:25+00:00","article_modified_time":"2019-01-21T18:15:03+00:00","author":"Christal Pollock, DVM, DABVP (Avian Practice)","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christal Pollock, DVM, DABVP (Avian Practice)","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/","url":"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/","name":"Cat\u00e9teres en Reptiles - LafeberVet","isPartOf":{"@id":"https:\/\/lafeber.com\/vet\/#website"},"datePublished":"2013-01-16T06:00:25+00:00","dateModified":"2019-01-21T18:15:03+00:00","breadcrumb":{"@id":"https:\/\/lafeber.com\/vet\/es\/catheters-in-reptiles\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"WebSite","@id":"https:\/\/lafeber.com\/vet\/#website","url":"https:\/\/lafeber.com\/vet\/","name":"LafeberVet","description":"El recurso para los profesionales veterinarios de animales ex\u00f3ticos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafeber.com\/vet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/posts\/20554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/comments?post=20554"}],"version-history":[{"count":0,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/posts\/20554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/media\/17656"}],"wp:attachment":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/media?parent=20554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/categories?post=20554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/tags?post=20554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}