{"id":50519,"date":"2020-06-06T20:36:17","date_gmt":"2020-06-07T01:36:17","guid":{"rendered":"https:\/\/lafeber.com\/vet\/capnometria-en-especies-exoticas\/"},"modified":"2020-06-06T22:11:06","modified_gmt":"2020-06-07T03:11:06","slug":"capnometria-en-especies-exoticas","status":"publish","type":"post","link":"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/","title":{"rendered":"Capnometr\u00eda en especies ex\u00f3ticas"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":12480,"featured_media":38568,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,507,822,333],"tags":[5561,5562,5563,2826,4144,5564,5565],"class_list":["post-50519","post","type-post","status-publish","format-standard","post-password-required","hentry","category-featured-content","category-restricted","category-restringido","category-sin-categorizar","tag-capnografia","tag-dioxido-de-carbono","tag-etco2-es","tag-intubacion","tag-monitoreo","tag-respiracion-es","tag-ventilacion-es","content_types-articulo","topics-analgesia-y-anestesiologia","topics-cuidado-critico","topics-respiratorio","species-aviar","species-conejo","species-huron","species-loro-gris-africano","species-mamiferos","species-psitacidas","species-reptiles-anfibios","contributor-barbara-ambros-drmedvet-mvetsc-decvaa","contributor-pollock-es","contributor-nugent-deal-es","contributor-katrina-lafferty-cvt-vts-anesthesiaanalgesia","rcp-is-restricted","rcp-no-access"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capnometr\u00eda en especies ex\u00f3ticas - LafeberVet<\/title>\n<meta name=\"description\" content=\"La capnometr\u00eda mide el valor m\u00e1ximo de di\u00f3xido de carbono (CO2) obtenido al final de la expiraci\u00f3n o al final del di\u00f3xido de carbono (ETCO2). Existe una buena correlaci\u00f3n entre ETCO2 y CO2 arterial en aves y mam\u00edferos, y la capnograf\u00eda puede usarse como una herramienta confiable para evaluar la adecuaci\u00f3n de la ventilaci\u00f3n en estas especies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capnometr\u00eda en especies ex\u00f3ticas - LafeberVet\" \/>\n<meta property=\"og:description\" content=\"La capnometr\u00eda mide el valor m\u00e1ximo de di\u00f3xido de carbono (CO2) obtenido al final de la expiraci\u00f3n o al final del di\u00f3xido de carbono (ETCO2). Existe una buena correlaci\u00f3n entre ETCO2 y CO2 arterial en aves y mam\u00edferos, y la capnograf\u00eda puede usarse como una herramienta confiable para evaluar la adecuaci\u00f3n de la ventilaci\u00f3n en estas especies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/\" \/>\n<meta property=\"og:site_name\" content=\"LafeberVet\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-07T01:36:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-07T03:11:06+00:00\" \/>\n<meta name=\"author\" content=\"Katrina Lafferty, RLAT, VTS (Anesthesia\/Analgesia)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katrina Lafferty, RLAT, VTS (Anesthesia\/Analgesia)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/es\\\/capnometria-en-especies-exoticas\\\/\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/es\\\/capnometria-en-especies-exoticas\\\/\",\"name\":\"Capnometr\u00eda en especies ex\u00f3ticas - LafeberVet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\"},\"datePublished\":\"2020-06-07T01:36:17+00:00\",\"dateModified\":\"2020-06-07T03:11:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/es\\\/capnometria-en-especies-exoticas\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/\",\"name\":\"LafeberVet\",\"description\":\"El recurso para los profesionales veterinarios de animales ex\u00f3ticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capnometr\u00eda en especies ex\u00f3ticas - LafeberVet","description":"La capnometr\u00eda mide el valor m\u00e1ximo de di\u00f3xido de carbono (CO2) obtenido al final de la expiraci\u00f3n o al final del di\u00f3xido de carbono (ETCO2). Existe una buena correlaci\u00f3n entre ETCO2 y CO2 arterial en aves y mam\u00edferos, y la capnograf\u00eda puede usarse como una herramienta confiable para evaluar la adecuaci\u00f3n de la ventilaci\u00f3n en estas especies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/","og_locale":"es_ES","og_type":"article","og_title":"Capnometr\u00eda en especies ex\u00f3ticas - LafeberVet","og_description":"La capnometr\u00eda mide el valor m\u00e1ximo de di\u00f3xido de carbono (CO2) obtenido al final de la expiraci\u00f3n o al final del di\u00f3xido de carbono (ETCO2). Existe una buena correlaci\u00f3n entre ETCO2 y CO2 arterial en aves y mam\u00edferos, y la capnograf\u00eda puede usarse como una herramienta confiable para evaluar la adecuaci\u00f3n de la ventilaci\u00f3n en estas especies.","og_url":"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/","og_site_name":"LafeberVet","article_published_time":"2020-06-07T01:36:17+00:00","article_modified_time":"2020-06-07T03:11:06+00:00","author":"Katrina Lafferty, RLAT, VTS (Anesthesia\/Analgesia)","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Katrina Lafferty, RLAT, VTS (Anesthesia\/Analgesia)","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/","url":"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/","name":"Capnometr\u00eda en especies ex\u00f3ticas - LafeberVet","isPartOf":{"@id":"https:\/\/lafeber.com\/vet\/#website"},"datePublished":"2020-06-07T01:36:17+00:00","dateModified":"2020-06-07T03:11:06+00:00","breadcrumb":{"@id":"https:\/\/lafeber.com\/vet\/es\/capnometria-en-especies-exoticas\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"WebSite","@id":"https:\/\/lafeber.com\/vet\/#website","url":"https:\/\/lafeber.com\/vet\/","name":"LafeberVet","description":"El recurso para los profesionales veterinarios de animales ex\u00f3ticos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafeber.com\/vet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/posts\/50519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/users\/12480"}],"replies":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/comments?post=50519"}],"version-history":[{"count":0,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/posts\/50519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/media\/38568"}],"wp:attachment":[{"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/media?parent=50519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/categories?post=50519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/es\/wp-json\/wp\/v2\/tags?post=50519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}