{"id":25318,"date":"2015-03-18T06:00:49","date_gmt":"2015-03-18T06:00:49","guid":{"rendered":"http:\/\/lafeber.com\/vet\/fr\/?p=25318"},"modified":"2025-04-24T10:42:37","modified_gmt":"2025-04-24T15:42:37","slug":"fiche-de-donnees-de-base-tortue-grecque","status":"publish","type":"post","link":"https:\/\/lafeber.com\/vet\/fr\/fiche-de-donnees-de-base-tortue-grecque\/","title":{"rendered":"Fiche d&#8217;informations de base : Tortue Grecque"},"content":{"rendered":"<h1>Tortue Grecque (<em>Testudo graeca <\/em>complex)<\/h1>\n<div id=\"attachment_19689\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoises-labeled.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19689\" class=\"wp-image-19689\" src=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoises-labeled.jpg\" alt=\"Greek or Spur-Thighed Tortoises\" width=\"600\" height=\"324\" srcset=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoises-labeled.jpg 700w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoises-labeled-500x270.jpg 500w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoises-labeled-400x216.jpg 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-19689\" class=\"wp-caption-text\"><em>Testudo graeca ibera<\/em> juv\u00e9nile (\u00e0 gauche); T. graeca graeca (\u00e0 droite). Cr\u00e9dit photo: Massimo Lazzari via Wikimedia Commons<\/p><\/div>\n<div class=\"ezcol ezcol-one-third\">\n<h2>Biologie<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\n<em>Testudo graeca ibera<\/em> partage de nombreuses similitudes avec Testudo hermanni en ce qui concerne leur environnement naturel, le climat, l\u2019alimentation, et la p\u00e9riode d&#8217;hibernation. L&#8217;habitat de ces esp\u00e8ces comprend des zones arides situ\u00e9es depuis le niveau de la mer jusqu\u2019\u00e0 plus de 3000 m d&#8217;altitude, mais leurs pr\u00e9f\u00e9rences environnementales sont les prairies, les for\u00eats les savanes.<\/p>\n<ul>\n<li><em>Testudo graeca graeca<\/em> sont retrouv\u00e9es depuis le nord du Maroc jusqu\u2019\u00e0 la Libye, au sud de l&#8217;Espagne, en Sardaigne et en Sicile.<\/li>\n<li><em>Testudo graeca terrestris<\/em> se trouvent dans le sud de la Turquie, la Syrie, le Liban, la Jordanie, de l&#8217;Isra\u00ebl \u00e0 l&#8217;Egypte, et au Nord de la Libye. Dans le commerce, ces animaux sont appel\u00e9s \u00ab Golden Greek Tortoise \u00bb en raison de leur carapace de couleur claire.<\/li>\n<li><em>Testudo graeca zarudnyi<\/em> se trouvent en Iran, en Afghanistan et au Pakistan.<\/li>\n<li><em>Testudo graeca ibera<\/em> se trouvent dans le nord-Gr\u00e8ce, une partie des Balkans, les \u00eeles de l&#8217;Eg\u00e9e du Nord, et certaines r\u00e9gions de Turquie, d\u2019Iran ou d&#8217;Irak.<\/li>\n<li>Comme la taxonomie de ces esp\u00e8ces est toujours remise en question, les sp\u00e9cimens retrouv\u00e9s dans le commerce peuvent appartenir \u00e0 diff\u00e9rentes sous-esp\u00e8ces<\/li>\n<\/ul>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Statut de conservation<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nLes populations sauvages sont class\u00e9es comme \u00abvuln\u00e9rable\u00bb sur la liste rouge de l&#8217;IUCN et sont inclus dans l&#8217;Annexe II de la CITES.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Taxonomie<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\n<strong>Clase<\/strong>: <em>Reptilia<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong>Ordre<\/strong>: <em>Chelonia\/Testudines<\/em><\/p>\n<p style=\"padding-left: 60px;\"><strong>Famile<\/strong>: <em>Testudinidae<\/em><\/p>\n<p style=\"padding-left: 90px;\"><strong>Genus<\/strong>: <a href=\"https:\/\/lafeber.com\/vet\/basic-information-sheet-mediterranean-tortoises\"><em>Testudo<\/em><\/a><\/p>\n<p style=\"padding-left: 120px;\"><em>Testudo graeca<\/em><\/p>\n<p style=\"padding-left: 150px;\"><em>Testudo graeca graeca<\/em><\/p>\n<p style=\"padding-left: 150px;\"><em>Testudo graeca terrestris<\/em><\/p>\n<p style=\"padding-left: 150px;\"><em>Testudo graeca zarudnyi<\/em><\/p>\n<p>La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab\u00a0tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme <em>Testudo graeca ibera<\/em>. Chitty (2013) indique que la tortue grecque (<em>Testudo graeca<\/em>) et la tortue d&#8217;ib\u00e9rie ou tortue levantine (<em>Testudo ibera<\/em>) sont des esp\u00e8ces tout \u00e0 fait distinctes. Une \u00e9tude publi\u00e9e dans Conservation Biology et Chelonian (2012) d\u00e9finie <em>Testudo graeca ibera<\/em> comme la tortue grecque eurasienne.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Description physique<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><\/p>\n<h3>Taille<\/h3>\n<p><em>Testudo graeca ibera<\/em> est une tortue de taille moyenne allant de 18 \u00e0 21 cm de longueur. <em>Testudo graeca graeca<\/em> est plus petite: 13-16 cm (Hernandez-Divers 2003). Cette esp\u00e8ce peut mesurer jusqu&#8217;\u00e0 30 cm de longueur avec un poids maximum d&#8217;environ 6 kg.<\/p>\n<h3>Couleur<\/h3>\n<p>La carapace est jaune brun\u00e2tre avec des taches noires. <em>Testudo ibera<\/em> est souvent plus p\u00e2le que <em>Testudo graeca<\/em>, bien que des populations plus sombres existent.<\/p>\n<p><em>Testudo ibera<\/em> a une carapace plus plate et plus large que <em>Testudo graeca<\/em>. La premi\u00e8re \u00e9caille vert\u00e9brale est plus anguleuse chez <em>Testudo ibera<\/em> alors qu\u2019elle est plus arrondie chez <em>Testudo graeca<\/em>.<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><div id=\"attachment_19697\" style=\"width: 260px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19697\" class=\"size-thumbnail wp-image-19697\" src=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description.jpg\" alt=\"Spur thighed tortise\" width=\"250\" height=\"250\" srcset=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description.jpg 700w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description-300x300.jpg 300w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description-100x100.jpg 100w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description-500x500.jpg 500w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description-250x250.jpg 250w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-Physical-Description-400x400.jpg 400w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><p id=\"caption-attachment-19697\" class=\"wp-caption-text\"><small><em>Testudo graeca ibera<\/em> Photo credit: Mayer Richard via Wikimedia Commons. <em>Click image to enlarge<\/em>.<\/small><\/p><\/div><\/td>\n<td>Testudo graeca peut \u00eatre distingu\u00e9e des autres membres du genre Testudo par la pr\u00e9sence d&#8217;un tuberculeux \u00e9largie (fl\u00e8ches gauche sur la photo ci-dessous) sur la cuisse m\u00e9diale et une \u00e9caille supracaudale unique. Parfois des \u00e9perons doubles ou triples sont pr\u00e9sents, l&#8217;un \u00e9tant dominante. Cette esp\u00e8ce n\u2019a pas de pointe corn\u00e9e \u00e0 l\u2019extr\u00e9mit\u00e9 de la queue.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>R\u00e9gime alimentaire<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nL&#8217;alimentation naturelle de <em>Testudo ibera<\/em> se compose d&#8217;une grande vari\u00e9t\u00e9 de plantes fibreuses, en particulier leurs fleurs (Divers 2003). <em>Testudo ibera<\/em> est plus omnivore que Testudo graeca et certains individus sauvages peuvent consommer des mollusques et des insectes. La majeure partie de l&#8217;alimentation en captivit\u00e9 se compose de l\u00e9gumes verts, d&#8217;herbes et de fleurs. Les tortues sont \u00e9galement nourries d\u2019autres v\u00e9g\u00e9taux ainsi que d&#8217;une petite quantit\u00e9 de fruits. Voir la fiche de donn\u00e9es de base tortues m\u00e9diterran\u00e9ennes pour plus d&#8217;informations.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Condition d\u2019\u00e9levage<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><\/p>\n<table>\n<tbody>\n<tr>\n<td rowspan=\"2\"><strong>Temp\u00e9rature<\/strong><\/td>\n<td><strong>Jour<\/strong><\/td>\n<td><strong>Point chaud<\/strong><\/td>\n<td><strong>Nuit<\/strong><\/td>\n<td><strong>R\u00e9f\u00e9rence<\/strong><\/td>\n<\/tr>\n<tr>\n<td>20\u00b0C-27\u00b0C\u00a0 (68\u00b0F &#8211; 81\u00b0F)<\/td>\n<td>G\u00e9n\u00e9ralement 5\u00b0C de plus que la temp\u00e9rature diurne<\/td>\n<td>Diminuer d\u2019environ 5\u00b0C<\/td>\n<td>Gibbons 2012, Divers 2003<\/td>\n<\/tr>\n<tr>\n<td><strong>Humidit\u00e9<\/strong><\/td>\n<td colspan=\"4\"><em>Testudo graeca<\/em> pr\u00e9f\u00e8re une humidit\u00e9 relative de 30-50% (Gibbons 2012). <em>Testudo graeca graeca<\/em> est particuli\u00e8rement sensible aux variations climatiques et n\u00e9cessite une humidit\u00e9 relative de 40-75% (Hern\u00e1ndez-Divers 2003).<\/td>\n<\/tr>\n<tr>\n<td><strong>Eclairage<\/strong><\/td>\n<td colspan=\"4\">Un \u00e9clairage artificiel UVB est recommand\u00e9 pour les animaux en captivit\u00e9. Voir la fiche de donn\u00e9es de base tortues m\u00e9diterran\u00e9enne pour plus d&#8217;informations<\/td>\n<\/tr>\n<tr>\n<td><strong>Taille et conception de la cage<\/strong><\/td>\n<td colspan=\"4\"><em>Testudo graeca ibera<\/em> sont des animaux rustiques et qui tol\u00e8rent relativement bien des variations climatiques. C\u2019est pour cela, qu\u2019elles sont le plus souvent h\u00e9berg\u00e9es dehors lors de l\u2019\u00e9t\u00e9. Voir la fiche de donn\u00e9es de base tortues m\u00e9diterran\u00e9enne pour plus d&#8217;informations.<\/td>\n<\/tr>\n<tr>\n<td><strong>Structure sociale<\/strong><\/td>\n<td colspan=\"4\"><em>Testudo graeca graeca<\/em> ne s\u2019adapte pas bien \u00e0 la pr\u00e9sence d\u2019autres esp\u00e8ces<\/td>\n<\/tr>\n<tr>\n<td><strong>Hibernation\/ estivation<\/strong><\/td>\n<td colspan=\"4\">L\u2019hibernation pour <em>Testudo graeca ibera<\/em> peut s\u2019\u00e9tendre de Novembre \u00e0 avril dans la nature. Cette esp\u00e8ce vivant en altitude survie \u00e0 des temp\u00e9ratures de 5 \u00e0 10\u00b0C (voir les recommandations d\u2019hibernation pour <em>Testudo marginata<\/em>) Ne jamais exposer les tortues \u00e0 des temp\u00e9ratures en dessous de 0\u00b0C. Les plus petites esp\u00e8ces que l\u2019on retrouve au niveau de la mer tendent \u00e0 ne pas hiverner. Au contraire, les <em>Testudo graeca graeca<\/em> sauvages peuvent estiver en s\u2019enterrant lors de fortes chaleur (Hern\u00e1ndez-Divers (2003).<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Valeurs physiologiques<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><\/p>\n<table>\n<tbody>\n<tr>\n<td><strong>Records de long\u00e9vit\u00e9:<\/strong><\/td>\n<td>127 ans dans la nature, au moins 57 ans en captivit\u00e9 La p\u00e9riode d&#8217;incubation est de 60 jours<\/td>\n<\/tr>\n<tr>\n<td><strong>La p\u00e9riode d&#8217;incubation<\/strong><\/td>\n<td>est de 60 jours<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Anatomie \/ physiologie<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nVoir la Fiche de Donn\u00e9es de base tortues m\u00e9diterran\u00e9ennes<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Manipulation<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nVoir la Fiche de Donn\u00e9es de base tortues m\u00e9diterran\u00e9ennes<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Ponction veineuse<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nVoir la Fiche de Donn\u00e9es de base tortues m\u00e9diterran\u00e9ennes<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>M\u00e9decine pr\u00e9ventive<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nVoir la Fiche de Donn\u00e9es de base tortues m\u00e9diterran\u00e9ennes<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Dominantes pathologiques<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nL\u2019herpesvirus 3 des tortues terrestres est souvent d\u00e9crit dans le genre Testudo. Les lithiases urinaires sont \u00e9galement un trouble relativement courante chez <em>Testudo graeca<\/em>.<br \/>\nAutres maladies rapport\u00e9es chez <em>T. graeca<\/em>:<\/p>\n<ul>\n<li>C\u00e9cit\u00e9 post-hibernation due \u00e0 des l\u00e9sions r\u00e9tiniennes (hypovitaminose A)<\/li>\n<li>Picornavirus est souvent isol\u00e9es chez <em>Testudo graeca<\/em><\/li>\n<li>Le genre Ferlavirus, un paramyxovirus a \u00e9galement \u00e9t\u00e9 d\u00e9tect\u00e9 chez <em>Testudo graeca<\/em>.<\/li>\n<\/ul>\n<p>Voir la Fiche de Donn\u00e9es de base tortues m\u00e9diterran\u00e9ennes pour plus d&#8217;informations.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Quiz<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\n<a href=\"https:\/\/lafeber.com\/vet\/fr\/quiz-connaissez-vous-bien-les-tortues-mediterraneennes\/\">Cliquez ici<\/a> pour acc\u00e9der au quiz tortues terrestres LafeberVet<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><\/p>\n<p>**<em>Login to view references<\/em>**<\/p>\n<h2 class=\"ref\">Bibliographie<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera&#8230;<\/p>\n","protected":false},"author":5,"featured_media":19693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[332],"tags":[1488,5944,1812,702],"class_list":["post-25318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-herbivore-fr","tag-histoire-naturelle","tag-taxonomie","tag-species-taxonomy","content_types-fiches-information","topics-elevage","topics-medecine-preventive","topics-nutrition-fr","species-reptiles-et-amphibiens","species-tortues","channel-documents-et-materiel-educatif","contributor-pignon-fr","contributor-pollock-fr","contributor-kanis-fr","contributor-latney-fr","contributor-donoghue-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiche d&#039;informations de base : Tortue Grecque - LafeberVet<\/title>\n<meta name=\"description\" content=\"La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiche d&#039;informations de base : Tortue Grecque - LafeberVet\" \/>\n<meta property=\"og:description\" content=\"La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/\" \/>\n<meta property=\"og:site_name\" content=\"LafeberVet\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-18T06:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T15:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoisesbasic-info.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christal Pollock, DVM, DABVP (Avian Practice)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christal Pollock, DVM, DABVP (Avian Practice)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/\"},\"author\":{\"name\":\"Christal Pollock, DVM, DABVP (Avian Practice)\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#\\\/schema\\\/person\\\/c81ad95bd36f6c15774985ab6dc5d274\"},\"headline\":\"Fiche d&#8217;informations de base : Tortue Grecque\",\"datePublished\":\"2015-03-18T06:00:49+00:00\",\"dateModified\":\"2025-04-24T15:42:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/\"},\"wordCount\":1215,\"image\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/Spur-thighed-tortoisesbasic-info.jpg\",\"keywords\":[\"herbivore\",\"histoire naturelle\",\"taxonomie\",\"taxonomy\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/\",\"name\":\"Fiche d'informations de base : Tortue Grecque - LafeberVet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/Spur-thighed-tortoisesbasic-info.jpg\",\"datePublished\":\"2015-03-18T06:00:49+00:00\",\"dateModified\":\"2025-04-24T15:42:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#\\\/schema\\\/person\\\/c81ad95bd36f6c15774985ab6dc5d274\"},\"description\":\"La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/Spur-thighed-tortoisesbasic-info.jpg\",\"contentUrl\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/Spur-thighed-tortoisesbasic-info.jpg\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/basic-information-sheet-greek-or-spur-thighed-tortoise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiche d&#8217;informations de base : Tortue Grecque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/\",\"name\":\"LafeberVet\",\"description\":\"La r\u00e9f\u00e9rence pour les v\u00e9t\u00e9rinaires d'animaux exotiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#\\\/schema\\\/person\\\/c81ad95bd36f6c15774985ab6dc5d274\",\"name\":\"Christal Pollock, DVM, DABVP (Avian Practice)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g\",\"caption\":\"Christal Pollock, DVM, DABVP (Avian Practice)\"},\"sameAs\":[\"https:\\\/\\\/lafeber.com\\\/vet\\\/pollock\\\/\"],\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/author\\\/christalp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiche d'informations de base : Tortue Grecque - LafeberVet","description":"La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/","og_locale":"fr_FR","og_type":"article","og_title":"Fiche d'informations de base : Tortue Grecque - LafeberVet","og_description":"La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera...","og_url":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/","og_site_name":"LafeberVet","article_published_time":"2015-03-18T06:00:49+00:00","article_modified_time":"2025-04-24T15:42:37+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoisesbasic-info.jpg","type":"image\/jpeg"}],"author":"Christal Pollock, DVM, DABVP (Avian Practice)","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christal Pollock, DVM, DABVP (Avian Practice)","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#article","isPartOf":{"@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/"},"author":{"name":"Christal Pollock, DVM, DABVP (Avian Practice)","@id":"https:\/\/lafeber.com\/vet\/#\/schema\/person\/c81ad95bd36f6c15774985ab6dc5d274"},"headline":"Fiche d&#8217;informations de base : Tortue Grecque","datePublished":"2015-03-18T06:00:49+00:00","dateModified":"2025-04-24T15:42:37+00:00","mainEntityOfPage":{"@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/"},"wordCount":1215,"image":{"@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#primaryimage"},"thumbnailUrl":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoisesbasic-info.jpg","keywords":["herbivore","histoire naturelle","taxonomie","taxonomy"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/","url":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/","name":"Fiche d'informations de base : Tortue Grecque - LafeberVet","isPartOf":{"@id":"https:\/\/lafeber.com\/vet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#primaryimage"},"image":{"@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#primaryimage"},"thumbnailUrl":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoisesbasic-info.jpg","datePublished":"2015-03-18T06:00:49+00:00","dateModified":"2025-04-24T15:42:37+00:00","author":{"@id":"https:\/\/lafeber.com\/vet\/#\/schema\/person\/c81ad95bd36f6c15774985ab6dc5d274"},"description":"La taxonomie des tortues grecques \u00e0 subit de nombreux changements depuis des d\u00e9cennies. Certaines sources utilisent les noms de \u00ab tortue grecque\u00bb et \u00abtortue d\u2019Ib\u00e9rie\u00bb de fa\u00e7on interchangeable, mais Mader (2006) a identifi\u00e9 celle que l\u2019on appelait la tortue grecque comme Testudo graeca ibera...","breadcrumb":{"@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#primaryimage","url":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoisesbasic-info.jpg","contentUrl":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Spur-thighed-tortoisesbasic-info.jpg","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/lafeber.com\/vet\/basic-information-sheet-greek-or-spur-thighed-tortoise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lafeber.com\/vet\/fr\/"},{"@type":"ListItem","position":2,"name":"Fiche d&#8217;informations de base : Tortue Grecque"}]},{"@type":"WebSite","@id":"https:\/\/lafeber.com\/vet\/#website","url":"https:\/\/lafeber.com\/vet\/","name":"LafeberVet","description":"La r\u00e9f\u00e9rence pour les v\u00e9t\u00e9rinaires d'animaux exotiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafeber.com\/vet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lafeber.com\/vet\/#\/schema\/person\/c81ad95bd36f6c15774985ab6dc5d274","name":"Christal Pollock, DVM, DABVP (Avian Practice)","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g","caption":"Christal Pollock, DVM, DABVP (Avian Practice)"},"sameAs":["https:\/\/lafeber.com\/vet\/pollock\/"],"url":"https:\/\/lafeber.com\/vet\/fr\/author\/christalp\/"}]}},"_links":{"self":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts\/25318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/comments?post=25318"}],"version-history":[{"count":1,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts\/25318\/revisions"}],"predecessor-version":[{"id":77269,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts\/25318\/revisions\/77269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/media\/19693"}],"wp:attachment":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/media?parent=25318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/categories?post=25318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/tags?post=25318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}