{"id":27068,"date":"2011-02-25T06:00:03","date_gmt":"2011-02-25T06:00:03","guid":{"rendered":"http:\/\/lafeber.com\/vet\/fr\/?p=27068"},"modified":"2016-04-21T17:07:59","modified_gmt":"2016-04-21T17:07:59","slug":"fiche-informations-de-base-rainette-de-white","status":"publish","type":"post","link":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/","title":{"rendered":"Fiche d&#8217;informations de base : Rainette de White"},"content":{"rendered":"<h1>Rainette de White (<em>Pelodryas caerulea<\/em>)<\/h1>\n<div id=\"attachment_11231\" style=\"width: 710px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Whites-Tree-frog-Dara-Kero-width-700.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11231\" class=\"size-full wp-image-11231\" src=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Whites-Tree-frog-Dara-Kero-width-700.jpg\" alt=\"Photo credit: Dara_Kero via Flickr Creative Commons\" width=\"700\" height=\"372\" srcset=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Whites-Tree-frog-Dara-Kero-width-700.jpg 700w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Whites-Tree-frog-Dara-Kero-width-700-500x266.jpg 500w, https:\/\/lafeber.com\/vet\/wp-content\/uploads\/Whites-Tree-frog-Dara-Kero-width-700-400x212.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-11231\" class=\"wp-caption-text\"><small> Cr\u00e9dit photo : Dara_Kero via Flickr Creative Commons<\/small><\/p><\/div>\n<div class=\"ezcol ezcol-one-third\">\n<h2>Histoire naturelle<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nLa rainette de White est originaire de l&#8217;Australie et de l&#8217;Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d&#8217;Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Taxonomie<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\n<strong>Classe<\/strong>: <em>Amphibia<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong>Ordre<\/strong>: <em>Anura<\/em><\/p>\n<p style=\"padding-left: 60px;\"><strong>Famille<\/strong>: <em>Hylidae<\/em> (tree frogs)<\/p>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Couleur et taille<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nCette grenouille de taille moyenne \u00e0 grande atteint 5 \u00e011 cm de longueur. La plupart des adultes p\u00e8sent 50-90 grammes. Les m\u00e2les sont plus petits que les femelles. Son dos est vert jade \u00e0 brun olive et ses l\u00e8vres sont verd\u00e2tre.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>R\u00e9gime alimentaire<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nCes grenouilles se nourrissent d\u2019une vari\u00e9t\u00e9 d&#8217;invert\u00e9br\u00e9s de taille appropri\u00e9e gut-charg\u00e9, principalement des insectes. Saupoudrer les aliments des juv\u00e9niles avec un suppl\u00e9ment de vitamines \/ min\u00e9raux deux fois par semaine. Compl\u00e9mentez l\u2019alimentation des adultes une fois par semaine. Nourrir les jeunes tous les jours et les adultes deux \u00e0 trois fois par semaine.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Condition d\u2019entretien<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><\/p>\n<table>\n<tbody>\n<tr>\n<td>Temp\u00e9rature<\/td>\n<td>Fournir un gradient de temp\u00e9rature de 24-32\u00b0C pendant la journ\u00e9e avec un point chaud \u00e0 35\u00b0C. La nuit, la temp\u00e9rature peut tomber \u00e0 18-21\u00b0C.<\/td>\n<\/tr>\n<tr>\n<td>Humidit\u00e9\/eau<\/td>\n<td>L\u2019objectif est une humidit\u00e9 relative de 60-70%. Fournir un plat d&#8217;eau peu profond et un peu de brume dans l&#8217;enceinte. Entre deux brumisation le substrat doit rester humide, mais pas inond\u00e9.<br \/>\nLes sources d&#8217;eau potentielles peuvent \u00eatre :<\/p>\n<ul>\n<li>Eau du robinet laiss\u00e9e repos\u00e9e dans un r\u00e9cipient ouvert pendant 24-48 heures afin que le chlore puisse se dissiper.<\/li>\n<li>Eau de source en bouteille<\/li>\n<li>Eau du robinet filtr\u00e9 : La faire passer dans un filtre de s\u00e9diment et de charbon active<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Taille et conception de la cage<\/td>\n<td>Cette grenouille calme ne n\u00e9cessite pas beaucoup d&#8217;espace. Une \u00e0 quatre grenouilles peuvent prosp\u00e9rer dans terrarium de 75 L. Un terrarium en configuration habitat bois\u00e9e est id\u00e9al, mais la rainette de White se contentera bien d\u2019une configuration simple..<\/td>\n<\/tr>\n<tr>\n<td>Equipement du terrarium<\/td>\n<td>Des serviettes en papier s\u00e8ches peuvent suffire comme substrat, mais il faut prendre soin de maintenir une humidit\u00e9 ad\u00e9quate. Fournir une grande branche d&#8217;arbre d\u2019un diam\u00e8tre au moins \u00e9quivalent au corps de la grenouille, ou un pot d&#8217;argile pour qu\u2019elle puisse se percher. Fournir une source de lumi\u00e8re de faible intensit\u00e9 d&#8217;\u00e9clairage \u00e0 spectre complet pour une absorption optimale du calcium alimentaire. Fournir des plantes pour qu\u2019elle puisse se cacher.<\/td>\n<\/tr>\n<tr>\n<td>Structure sociale<\/td>\n<td>Vie en communaut\u00e9<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Esperance de vie<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\n20+ years<br \/>\n20 ans<br \/>\nLes rainettes de White atteignent souvent leur maturit\u00e9 sexuelle au cours de leur deuxi\u00e8me ann\u00e9e de vie.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Anatomy\/ physiology<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><\/p>\n<table>\n<tbody>\n<tr>\n<td>Dermatologie :<\/td>\n<td>La peau de la grenouille est un organe dynamique impliqu\u00e9 dans l&#8217;hydratation et l&#8217;\u00e9quilibre \u00e9lectrolytique, la synth\u00e8se et la s\u00e9cr\u00e9tion de produits chimiques, et de l&#8217;immunit\u00e9. De mauvaises conditions d\u2019entretiens peuvent entra\u00eener une maladie de la peau qui peut rapidement tuer le patient.<br \/>\nLes grenouilles muent r\u00e9guli\u00e8rement et ing\u00e8rent leur peau \u00e0 mesure qu\u2019ils grandissent. Juste avant la mue, la peau apparaitra terne.<\/td>\n<\/tr>\n<tr>\n<td>Gastro-intestinal :<\/td>\n<td>Tractus gastro-intestinal cout et simple qui se jette dans un cloaque<\/td>\n<\/tr>\n<tr>\n<td>Cardiaque :<\/td>\n<td>Un c\u0153ur \u00e0 trois cavit\u00e9s est enferm\u00e9 \u00e0 l&#8217;int\u00e9rieur de la ceinture scapulaire.<\/td>\n<\/tr>\n<tr>\n<td>Syst\u00e8me lymphatique :<\/td>\n<td>Tous les amphibiens poss\u00e8dent des c\u0153urs lymphatiques, qui battent de mani\u00e8re synchrone ind\u00e9pendamment du c\u0153ur.<\/td>\n<\/tr>\n<tr>\n<td>Urog\u00e9nital :<\/td>\n<td>Un syst\u00e8me de portail r\u00e9nale est pr\u00e9sent<\/td>\n<\/tr>\n<tr>\n<td>Dimorphisme sexuel :<\/td>\n<td>Les m\u00e2les adultes sont environ 30-50% plus petit que les femelles adultes. Durant la saison de reproduction, les m\u00e2les \u00ab appellent \u00bb les femelles, ils d\u00e9velopperont \u00e9galement des petits coussinets nuptiaux bruns sur chaque pouce.<\/td>\n<\/tr>\n<tr>\n<td>Divers :<\/td>\n<td>Les grenouilles poss\u00e8dent corps gras c\u0153lomiques et inguinales.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Contention<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nLa peau des amphibiens est tr\u00e8s sensible il faut donc manipuler les grenouilles le moins possible. Pour restreindre manuellement les grenouilles, porter des gants chirurgicaux humides.<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Prise de sang<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nVeine abdominale ventrale<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>M\u00e9decine pr\u00e9ventive<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><br \/>\nEffectuer un <a title=\" \u00c9valuation clinique de la grenouille ou crapaud\" href=\" https:\/\/lafeber.com\/vet\/fr\/evaluation-clinique-de-la-grenouille-ou-crapaud\/\">un examen visuel<\/a> en pla\u00e7ant la grenouille dans une bo\u00eete en plastique transparent ou dans un bac rempli d\u2019eau.<br \/>\nExamen clinique (au besoin).<br \/>\nAnalyse des parasites f\u00e9caux<br \/>\n<\/div><div class=\"ezcol-divider\"><\/div><br \/>\n<div class=\"ezcol ezcol-one-third\"><\/p>\n<h2>Dominantes pathologiques<\/h2>\n<p><\/div><br \/>\n<div class=\"ezcol ezcol-two-third ezcol-last\"><\/p>\n<ul>\n<li>Chytridiomycose<\/li>\n<li>Endoparasitisme<\/li>\n<li>Hyperparathyro\u00efdie secondaire nutritionnel ou \u00ab maladie m\u00e9tabolique des os \u00bb (T\u00e9l\u00e9charger la fiche client : <a title=\"Metabolic Bone Disease in Reptiles and Amphibians\" href=\"https:\/\/lafeber.com\/vet\/metabolic-bone-disease-in-reptiles-and-amphibians\/\"> Metabolic Bone Disease dans Reptiles et amphibiens <\/a>).<\/li>\n<li>Ob\u00e9sit\u00e9<\/li>\n<li>Syndrome \u00ab red leg \u00bb<\/li>\n<\/ul>\n<p><\/div><div class=\"ezcol-divider\"><\/div><\/p>\n<p>**<em> Connectez-vous pour voir les r\u00e9f\u00e9rences <\/em>**<\/p>\n<h2 class=\"ref\">Bibliographie<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>La rainette de White est originaire de l&#8217;Australie et de l&#8217;Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d&#8217;Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial&#8230;<\/p>\n","protected":false},"author":5,"featured_media":4513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[332],"tags":[396],"class_list":["post-27068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-natural-history-fr","content_types-fiches-information","topics-anatomie-physiologie","topics-elevage","topics-medecine-preventive","species-amphibiens","species-reptiles-et-amphibiens","channel-documents-et-materiel-educatif","contributor-pignon-fr","contributor-pollock-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiche d&#039;informations de base : Rainette de White - LafeberVet<\/title>\n<meta name=\"description\" content=\"La rainette de White est originaire de l&#039;Australie et de l&#039;Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d&#039;Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiche d&#039;informations de base : Rainette de White - LafeberVet\" \/>\n<meta property=\"og:description\" content=\"La rainette de White est originaire de l&#039;Australie et de l&#039;Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d&#039;Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/\" \/>\n<meta property=\"og:site_name\" content=\"LafeberVet\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-25T06:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-21T17:07:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/whites-tree-frog-feaured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"167\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christal Pollock, DVM, DABVP (Avian Practice)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christal Pollock, DVM, DABVP (Avian Practice)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/\"},\"author\":{\"name\":\"Christal Pollock, DVM, DABVP (Avian Practice)\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#\\\/schema\\\/person\\\/c81ad95bd36f6c15774985ab6dc5d274\"},\"headline\":\"Fiche d&#8217;informations de base : Rainette de White\",\"datePublished\":\"2011-02-25T06:00:03+00:00\",\"dateModified\":\"2016-04-21T17:07:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/\"},\"wordCount\":877,\"image\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/whites-tree-frog-feaured.jpg\",\"keywords\":[\"histoire naturelle\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/\",\"name\":\"Fiche d'informations de base : Rainette de White - LafeberVet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/whites-tree-frog-feaured.jpg\",\"datePublished\":\"2011-02-25T06:00:03+00:00\",\"dateModified\":\"2016-04-21T17:07:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#\\\/schema\\\/person\\\/c81ad95bd36f6c15774985ab6dc5d274\"},\"description\":\"La rainette de White est originaire de l'Australie et de l'Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d'Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/whites-tree-frog-feaured.jpg\",\"contentUrl\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/wp-content\\\/uploads\\\/whites-tree-frog-feaured.jpg\",\"width\":167,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/fiche-informations-de-base-rainette-de-white\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiche d&#8217;informations de base : Rainette de White\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#website\",\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/\",\"name\":\"LafeberVet\",\"description\":\"La r\u00e9f\u00e9rence pour les v\u00e9t\u00e9rinaires d'animaux exotiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/#\\\/schema\\\/person\\\/c81ad95bd36f6c15774985ab6dc5d274\",\"name\":\"Christal Pollock, DVM, DABVP (Avian Practice)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g\",\"caption\":\"Christal Pollock, DVM, DABVP (Avian Practice)\"},\"sameAs\":[\"https:\\\/\\\/lafeber.com\\\/vet\\\/pollock\\\/\"],\"url\":\"https:\\\/\\\/lafeber.com\\\/vet\\\/fr\\\/author\\\/christalp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiche d'informations de base : Rainette de White - LafeberVet","description":"La rainette de White est originaire de l'Australie et de l'Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d'Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/","og_locale":"fr_FR","og_type":"article","og_title":"Fiche d'informations de base : Rainette de White - LafeberVet","og_description":"La rainette de White est originaire de l'Australie et de l'Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d'Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial...","og_url":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/","og_site_name":"LafeberVet","article_published_time":"2011-02-25T06:00:03+00:00","article_modified_time":"2016-04-21T17:07:59+00:00","og_image":[{"width":167,"height":160,"url":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/whites-tree-frog-feaured.jpg","type":"image\/jpeg"}],"author":"Christal Pollock, DVM, DABVP (Avian Practice)","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christal Pollock, DVM, DABVP (Avian Practice)","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#article","isPartOf":{"@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/"},"author":{"name":"Christal Pollock, DVM, DABVP (Avian Practice)","@id":"https:\/\/lafeber.com\/vet\/#\/schema\/person\/c81ad95bd36f6c15774985ab6dc5d274"},"headline":"Fiche d&#8217;informations de base : Rainette de White","datePublished":"2011-02-25T06:00:03+00:00","dateModified":"2016-04-21T17:07:59+00:00","mainEntityOfPage":{"@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/"},"wordCount":877,"image":{"@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#primaryimage"},"thumbnailUrl":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/whites-tree-frog-feaured.jpg","keywords":["histoire naturelle"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/","url":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/","name":"Fiche d'informations de base : Rainette de White - LafeberVet","isPartOf":{"@id":"https:\/\/lafeber.com\/vet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#primaryimage"},"image":{"@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#primaryimage"},"thumbnailUrl":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/whites-tree-frog-feaured.jpg","datePublished":"2011-02-25T06:00:03+00:00","dateModified":"2016-04-21T17:07:59+00:00","author":{"@id":"https:\/\/lafeber.com\/vet\/#\/schema\/person\/c81ad95bd36f6c15774985ab6dc5d274"},"description":"La rainette de White est originaire de l'Australie et de l'Indon\u00e9sie. Elle est aussi connue sous le nom de Rainette car\u00e9ul\u00e9enne. Cette esp\u00e8ce est \u00e9lev\u00e9s en captivit\u00e9 en grand nombre. Les grenouilles sauvages captur\u00e9es en provenance d'Indon\u00e9sie sont \u00e9galement encore dans le circuit commercial...","breadcrumb":{"@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#primaryimage","url":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/whites-tree-frog-feaured.jpg","contentUrl":"https:\/\/lafeber.com\/vet\/wp-content\/uploads\/whites-tree-frog-feaured.jpg","width":167,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/lafeber.com\/vet\/fr\/fiche-informations-de-base-rainette-de-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lafeber.com\/vet\/fr\/"},{"@type":"ListItem","position":2,"name":"Fiche d&#8217;informations de base : Rainette de White"}]},{"@type":"WebSite","@id":"https:\/\/lafeber.com\/vet\/#website","url":"https:\/\/lafeber.com\/vet\/","name":"LafeberVet","description":"La r\u00e9f\u00e9rence pour les v\u00e9t\u00e9rinaires d'animaux exotiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafeber.com\/vet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lafeber.com\/vet\/#\/schema\/person\/c81ad95bd36f6c15774985ab6dc5d274","name":"Christal Pollock, DVM, DABVP (Avian Practice)","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/630858437627f3b0df3307fa2c64c7b0971a8f8fa56f1705ca7b3df8420c9cf1?s=96&d=mm&r=g","caption":"Christal Pollock, DVM, DABVP (Avian Practice)"},"sameAs":["https:\/\/lafeber.com\/vet\/pollock\/"],"url":"https:\/\/lafeber.com\/vet\/fr\/author\/christalp\/"}]}},"_links":{"self":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts\/27068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/comments?post=27068"}],"version-history":[{"count":0,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/posts\/27068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/media\/4513"}],"wp:attachment":[{"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/media?parent=27068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/categories?post=27068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lafeber.com\/vet\/fr\/wp-json\/wp\/v2\/tags?post=27068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}